{"id":14254,"date":"2015-03-10T15:08:22","date_gmt":"2015-03-10T18:08:22","guid":{"rendered":"https:\/\/www.csem.org.br\/?post_type=csem_em_foco&#038;p=14254"},"modified":"2023-07-21T16:25:52","modified_gmt":"2023-07-21T19:25:52","slug":"chamada-para-artigos-remhu-45","status":"publish","type":"csem_em_foco","link":"https:\/\/www.csem.org.br\/pt_br\/csem_em_foco\/chamada-para-artigos-remhu-45\/","title":{"rendered":"Chamada para artigos REMHU 45"},"content":{"rendered":"<p class=\"ygrps-yiv-1008543602msonormal\" style=\"text-align: justify;\">A\u00a0<strong>REMHU, Revista Interdisciplinar da Mobilidade Humana\u00a0<\/strong>(<a href=\"https:\/\/www.csem.org.br\/remhu\">www.csem.org.br\/remhu<\/a>\u00a0ou\u00a0<a href=\"http:\/\/www.scielo.br\/remhu\" target=\"_blank\" rel=\"noopener\">www.scielo.br\/remhu<\/a>), comunica que no segundo semestre de 2015 ser\u00e1 publicado o n. 45 da revista com um DOSSI\u00ca sobre o tema \u201c<strong>CRIMINALIZA\u00c7\u00c3O DAS MIGRA\u00c7\u00d5ES E DOS MIGRANTES<\/strong>\u201d.<\/p>\n<p class=\"ygrps-yiv-1008543602msonormal\">O objetivo do DOSSI\u00ca \u00e9 abordar temas como:<\/p>\n<ul>\n<li class=\"ygrps-yiv-1008543602msonormal\">pol\u00edticas e legisla\u00e7\u00f5es que criminalizam a migra\u00e7\u00e3o irregular<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">representa\u00e7\u00f5es sociais veiculadas por meios de comunica\u00e7\u00e3o que identificam os migrantes com criminosos, terroristas ou, de alguma forma, seres indesej\u00e1veis (a constru\u00e7\u00e3o social do \u201cinimigo\u201d)<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">delinqu\u00eancia e migra\u00e7\u00e3o (incid\u00eancia dos imigrantes no aumento ou diminui\u00e7\u00e3o de atividades ilegais no pa\u00eds receptor)<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">imigra\u00e7\u00e3o e terrorismo<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">a utiliza\u00e7\u00e3o da deten\u00e7\u00e3o preventiva dos migrantes (e a deporta\u00e7\u00e3o) como meio ordin\u00e1rio para a gest\u00e3o dos fluxos<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">a \u201cind\u00fastria\u201d da criminaliza\u00e7\u00e3o dos migrantes (por exemplo, o sistema penal privatizado)<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">a criminaliza\u00e7\u00e3o dos migrantes como legitimadora da discrimina\u00e7\u00e3o e viola\u00e7\u00e3o dos direitos dos migrantes ou da implementa\u00e7\u00e3o de pol\u00edticas de securitiza\u00e7\u00e3o<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">a imigra\u00e7\u00e3o \u201ccriminalizada\u201d enquanto causa de crises econ\u00f4micas e sociais nos pa\u00edses receptores (o migrante como bode expiat\u00f3rio)<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">criminaliza\u00e7\u00e3o dos migrantes e discrimina\u00e7\u00e3o de classe social, g\u00eanero, ra\u00e7a e religi\u00e3o<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">a \u201ccriminaliza\u00e7\u00e3o da solidariedade\u201d (puni\u00e7\u00e3o de atos de solidariedade junto a migrantes irregulares)<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">estrat\u00e9gias de adapta\u00e7\u00e3o individuais e coletivas dos migrantes diante de contextos de criminaliza\u00e7\u00e3o<\/li>\n<li class=\"ygrps-yiv-1008543602msonormal\">&#8230; outros.<\/li>\n<\/ul>\n<p class=\"ygrps-yiv-1008543602msonormal\">Al\u00e9m do dossi\u00ea, a revista REMHU inclui tamb\u00e9m uma SEC\u00c7\u00c3O ARTIGOS referente a\u00a0<strong>qualquer assunto relacionado com as migra\u00e7\u00f5es nacionais e internacionais<\/strong>: trabalhos para esta sec\u00e7\u00e3o podem ser submetidos para avalia\u00e7\u00e3o.<\/p>\n<p class=\"ygrps-yiv-1008543602msonormal\">Todos os artigos devem ser enviados diretamente pelo site da revista\u00a0<a href=\"https:\/\/www.csem.org.br\/remhu\">www.csem.org.br\/remhu<\/a>\u00a0ou, caso haja dificuldades, mediante o e-mail\u00a0<a href=\"mailto:remhu@csem.org.br\">remhu@csem.org.br<\/a>\u00a0at\u00e9 o dia\u00a0<strong>30 de junho de 2015<\/strong>. As normas bibliogr\u00e1ficas que devem ser adotadas pelos autores e outras informa\u00e7\u00f5es encontram-se no site da REMHU (<a href=\"https:\/\/www.csem.org.br\/remhu\">www.csem.org.br\/remhu<\/a>) ou no site da Cole\u00e7\u00e3o SciELO (<a href=\"http:\/\/www.scielo.br\/remhu\" target=\"_blank\" rel=\"noopener\">www.scielo.br\/remhu<\/a>). Para qualquer informa\u00e7\u00e3o ou d\u00favida entrar em contato no e-mail\u00a0<a href=\"mailto:remhu@csem.org.br\">remhu@csem.org.br<\/a>.<\/p>\n<p class=\"ygrps-yiv-1008543602msonormal\">Lembramos que em junho sair\u00e1 a\u00a0<strong>REMHU n. 44<\/strong>\u00a0com o dossi\u00ea sobre o tema \u201c<strong>MIGRA\u00c7\u00d5ES E ESPA\u00c7OS DE FRONTEIRA<\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","categories":[40],"class_list":["post-14254","csem_em_foco","type-csem_em_foco","status-publish","hentry","category-40"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.csem.org.br\/pt_br\/wp-json\/wp\/v2\/csem_em_foco\/14254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csem.org.br\/pt_br\/wp-json\/wp\/v2\/csem_em_foco"}],"about":[{"href":"https:\/\/www.csem.org.br\/pt_br\/wp-json\/wp\/v2\/types\/csem_em_foco"}],"wp:attachment":[{"href":"https:\/\/www.csem.org.br\/pt_br\/wp-json\/wp\/v2\/media?parent=14254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csem.org.br\/pt_br\/wp-json\/wp\/v2\/categories?post=14254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}