{"id":17946,"date":"2020-05-23T14:42:53","date_gmt":"2020-05-23T17:42:53","guid":{"rendered":"https:\/\/www.csem.org.br\/?post_type=csem_em_foco&#038;p=17946"},"modified":"2023-07-21T16:20:35","modified_gmt":"2023-07-21T19:20:35","slug":"plataformas-digitais-promovem-facilitam-o-acesso-de-migrantes-e-refugiadosas-a-informacoes-essenciais-para-sua-trajetoria-de-migracao","status":"publish","type":"csem_em_foco","link":"https:\/\/www.csem.org.br\/es\/csem_em_foco\/plataformas-digitais-promovem-facilitam-o-acesso-de-migrantes-e-refugiadosas-a-informacoes-essenciais-para-sua-trajetoria-de-migracao\/","title":{"rendered":"Plataformas digitais promovem e facilitam o acesso de migrantes e refugiados(as) a informa\u00e7\u00f5es essenciais"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Mundo afora, diversos servi\u00e7os online se espalham para auxiliar pessoas em situa\u00e7\u00e3o de mobilidade <\/em><\/p>\n<p>Segundo os \u00faltimos dados do Alto Comissariado das Na\u00e7\u00f5es Unidas para os Refugiados (ACNUR) de 2019, <a href=\"https:\/\/nacoesunidas.org\/numero-de-pessoas-deslocadas-no-mundo-chega-a-708-milhoes-diz-acnur\/\" target=\"_blank\" rel=\"noopener noreferrer\">existem mais de setenta milh\u00f5es de pessoas no mundo que se deslocaram de suas na\u00e7\u00f5es de maneira for\u00e7ada por conflitos pol\u00edticos, sociais e ambientais.<\/a> Essa popula\u00e7\u00e3o chega aos pa\u00edses em situa\u00e7\u00e3o de vulnerabilidade, sem acesso aos meios e informa\u00e7\u00f5es essenciais para sua sobreviv\u00eancia, na maioria dos casos sem compreender o idioma de seu destino.<\/p>\n<p>A partir de sua chegada, se inicia uma longa jornada desses refugiados(as) junto a organiza\u00e7\u00f5es da sociedade civil e governos, que se articulam para acolher e promover o acesso aos servi\u00e7os b\u00e1sicos de documenta\u00e7\u00e3o, sa\u00fade, trabalho e educa\u00e7\u00e3o. Entretanto, a maior dificuldade e principal necessidade dessas pessoas durante sua trajet\u00f3ria de migra\u00e7\u00e3o \u00e9 alcan\u00e7ar tais informa\u00e7\u00f5es e usufruir desses direitos.<\/p>\n<p>Nesse sentido, a internet \u00e9 um dos principais canais que disponibiliza tais esclarecimentos. Muitas dessas pessoas compartilham aparelhos celulares para se comunicar, segundo pesquisa da ACNUR de 2016, 93% desses povos vive em locais com cobertura de rede, por\u00e9m, possuem 50% menos de chances de possuir um aparelho com conex\u00e3o \u00e0 internet do que a popula\u00e7\u00e3o em geral. No Brasil, <a href=\"https:\/\/www.acnur.org\/portugues\/2020\/02\/03\/com-celulares-na-mao-venezuelanas-acessam-direitos-e-encurtam-distancias-no-brasil\/\" target=\"_blank\" rel=\"noopener noreferrer\">70% dos refugiados(as) e migrantes venezuelanos t\u00eam acesso a um celular.<\/a><\/p>\n<p>Plataformas online como sites e aplicativos s\u00e3o criados para garantir maior alcance e facilitar o acesso \u00e0 localiza\u00e7\u00e3o, servi\u00e7os relacionados a documenta\u00e7\u00e3o, moradia, sa\u00fade, assist\u00eancia social e jur\u00eddica e educa\u00e7\u00e3o. Os refugiados(as) que chegam em solo brasileiro podem solicitar o reconhecimento de sua condi\u00e7\u00e3o pelo sistema online SISCONARE, e o site HELP, da ACNUR, divulga informa\u00e7\u00f5es em cinco idiomas &#8211; portugu\u00eas, ingl\u00eas, espanhol, franc\u00eas e \u00e1rabe.<\/p>\n<p>Durante a pandemia do novo Coronav\u00edrus, muitos refugiados(as) j\u00e1 estabelecidos tamb\u00e9m utilizam os meios online para se manterem financeiramente e promover a valoriza\u00e7\u00e3o de sua cultura e o compartilhamento de seus conhecimentos, oferecendo de cursos de idiomas, aulas de gastronomia, oficinas de dan\u00e7a, m\u00fasica e poesia.<\/p>\n<p>Algumas dessas plataformas s\u00e3o o <a href=\"https:\/\/www.migraflix.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Migraflix<\/a> de capacita\u00e7\u00e3o profissional e gera\u00e7\u00e3o de renda, <a href=\"https:\/\/www.opentastebrasil.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Open Taste<\/a> que articula uma rede de chefes do mundo inteiro compartilhando conhecimentos gastr\u00f4nomicos e a<a href=\"http:\/\/www.abracocultural.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\"> ONG Abra\u00e7o cultural<\/a>, que oferece cursos de idiomas e cultura.<\/p>\n<p>No Brasil e mundo afora diversas outras plataformas divulgam informa\u00e7\u00f5es essenciais:<\/p>\n<ul>\n<li><a href=\"https:\/\/igarape.org.br\/oka\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aplicativo OKA &#8211; re\u00fane informa\u00e7\u00f5es sobre servi\u00e7os para a popula\u00e7\u00e3o migrante em quatro idiomas &#8211; portugu\u00eas, espanhol, ingl\u00eas e franc\u00eas. A plataforma n\u00e3o necessita de acesso \u00e0 internet.\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.thedream.us\/news\/daca-scholars-app\/\" target=\"_blank\" rel=\"noopener noreferrer\">Daca Scholars \u2013 compartilha dicas de bolsas de estudo para migrantes.<\/a><\/li>\n<li><a href=\"https:\/\/www.tarjim.ly\/pt\" target=\"_blank\" rel=\"noopener noreferrer\">Tarjimly \u2013 conecta volunt\u00e1rios dispostos a fazer tradu\u00e7\u00f5es por telefone e v\u00eddeo chamada para refugiados(as).\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/refunite.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Refunite \u2013 conecta v\u00edtimas de deslocamento for\u00e7ado \u00e0s suas fam\u00edlias.\u00a0<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><em>Luana G. Silveira<br \/>\n<\/em><em>Equipe de comunica\u00e7\u00e3o &#8211; CSEM<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>","protected":false},"featured_media":17947,"parent":0,"template":"","categories":[45],"class_list":["post-17946","csem_em_foco","type-csem_em_foco","status-publish","has-post-thumbnail","hentry","category-45"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/csem_em_foco\/17946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/csem_em_foco"}],"about":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/types\/csem_em_foco"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/media\/17947"}],"wp:attachment":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/media?parent=17946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/categories?post=17946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}