{"id":14286,"date":"2015-11-18T09:44:01","date_gmt":"2015-11-18T11:44:01","guid":{"rendered":"https:\/\/www.csem.org.br\/?post_type=csem_em_foco&#038;p=14286"},"modified":"2023-07-21T16:25:33","modified_gmt":"2023-07-21T19:25:33","slug":"hataraku-mao-sama","status":"publish","type":"csem_em_foco","link":"https:\/\/www.csem.org.br\/es\/csem_em_foco\/hataraku-mao-sama\/","title":{"rendered":"Hataraku Mao-sama"},"content":{"rendered":"<p>O Programa de P\u00f3s-Gradua\u00e7\u00e3o em Desenvolvimento, Sociedade e Coopera\u00e7\u00e3o Internacional \u2013 PPG-DSCI\/CEAM e o Centro Scalabriniano de Estudos Migrat\u00f3rios \u2013 CSEM, em parceria com o Observat\u00f3rio das Migra\u00e7\u00f5es Internacionais &#8211; OBMIGRA, realizar\u00e3o no pr\u00f3ximo dia 26 o<strong>\u00a0lan\u00e7amento do livro Pol\u00edica migrat\u00f3ria e o paradoxo da globlaiza\u00e7\u00e3o<\/strong>.<\/p>\n<p>O evento ser\u00e1 durante o Di\u00e1logos do Observat\u00f3rio, que tratar\u00e1 o tema &#8220;Migra\u00e7\u00e3o e cultura&#8221; com a palestra do Prof. Dr Roque Laraia (DAN\/UnB).<\/p>\n<p>Maiores informa\u00e7\u00f5es e confirma\u00e7\u00e3o de presen\u00e7a:\u00a0<a href=\"mailto:estudos2@csem.org.br\">estudos2@csem.org.br<\/a>\u00a0o\u00a0<a href=\"mailto:eventos.obmigra@gmail.com\">eventos.obmigra@gmail.com<\/a>\u00a0.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-600 wp-image-14287\" src=\"https:\/\/www.csem.org.br\/wp-content\/uploads\/2018\/08\/Divulgacao-600x875.jpg\" alt=\"\" width=\"600\" height=\"875\" title=\"\"><\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":0,"parent":0,"template":"","categories":[40],"class_list":["post-14286","csem_em_foco","type-csem_em_foco","status-publish","hentry","category-40"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/csem_em_foco\/14286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/csem_em_foco"}],"about":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/types\/csem_em_foco"}],"wp:attachment":[{"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/media?parent=14286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csem.org.br\/es\/wp-json\/wp\/v2\/categories?post=14286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}